{"id":439,"date":"2020-09-21T20:41:02","date_gmt":"2020-09-21T20:41:02","guid":{"rendered":"https:\/\/eledecolombia.com.co\/wordpress\/?page_id=439"},"modified":"2022-03-04T15:35:36","modified_gmt":"2022-03-04T15:35:36","slug":"login","status":"publish","type":"page","link":"https:\/\/eledecolombia.com.co\/wordpress\/login\/","title":{"rendered":"Cuenta"},"content":{"rendered":"<div id=\"pl-439\"  class=\"panel-layout\" >\n<div id=\"pg-439-0\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-439-0-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-439-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\n<div class=\"um um-login um-435\">\n\t<div class=\"um-form\">\n\t\t<form method=\"post\" action=\"\" autocomplete=\"off\">\n\t\t\t<div class=\"um-row _um_row_1 \" style=\"margin: 0 0 30px 0;\"><div class=\"um-col-1\"><div  id=\"um_field_435_username\" class=\"um-field um-field-text  um-field-username um-field-text um-field-type_text\" data-key=\"username\"><div class=\"um-field-label\"><label for=\"username-435\">Username or E-mail<span class=\"um-req\" title=\"Obligatorio\">*<\/span><\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input  autocomplete=\"off\" class=\"um-form-field valid \" type=\"text\" name=\"username-435\" id=\"username-435\" value=\"\" placeholder=\"\" data-validate=\"unique_username_or_email\" data-key=\"username\"  aria-invalid=\"false\" \/>\n\n\t\t\t\t\t\t<\/div><\/div><div  id=\"um_field_435_user_password\" class=\"um-field um-field-password  um-field-user_password um-field-password um-field-type_password\" data-key=\"user_password\"><div class=\"um-field-label\"><label for=\"user_password-435\">Contrase\u00f1a<span class=\"um-req\" title=\"Obligatorio\">*<\/span><\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input class=\"um-form-field valid \" type=\"password\" name=\"user_password-435\" id=\"user_password-435\" value=\"\" placeholder=\"\" data-validate=\"\" data-key=\"user_password\"  aria-invalid=\"false\" \/>\n\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/div>\t<input type=\"hidden\" name=\"form_id\" id=\"form_id_435\" value=\"435\" \/>\n\t\t<p class=\"um_request_name\">\n\t\t<label for=\"um_request_435\">Only fill in if you are not human<\/label>\n\t\t<input type=\"hidden\" name=\"um_request\" id=\"um_request_435\" class=\"input\" value=\"\" size=\"25\" autocomplete=\"off\" \/>\n\t<\/p>\n\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"d540cd4ef1\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/wordpress\/wp-json\/wp\/v2\/pages\/439\" \/>\n\t<div class=\"um-col-alt\">\n\n\t\t\n\n\t\t\t<div class=\"um-field um-field-c\">\n\t\t\t\t<div class=\"um-field-area\">\n\t\t\t\t\t<label class=\"um-field-checkbox\">\n\t\t\t\t\t\t<input type=\"checkbox\" name=\"rememberme\" value=\"1\"  \/>\n\t\t\t\t\t\t<span class=\"um-field-checkbox-state\"><i class=\"um-icon-android-checkbox-outline-blank\"><\/i><\/span>\n\t\t\t\t\t\t<span class=\"um-field-checkbox-option\"> Mantenerme conectado<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"um-clear\"><\/div>\n\t\t\n\t\t\t<div class=\"um-left um-half\">\n\t\t\t\t<input type=\"submit\" value=\" Iniciar sesi\u00f3n\" class=\"um-button\" id=\"um-submit-btn\" \/>\n\t\t\t<\/div>\n\t\t\t<div class=\"um-right um-half\">\n\t\t\t\t<a href=\"https:\/\/eledecolombia.com.co\/wordpress\/register\/\" class=\"um-button um-alt\">\n\t\t\t\t\tRegistrar\t\t\t\t<\/a>\n\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"um-clear\"><\/div>\n\n\t<\/div>\n\n\t\n\t<div class=\"um-col-alt-b\">\n\t\t<a href=\"https:\/\/eledecolombia.com.co\/wordpress\/password-reset\/\" class=\"um-link-alt\">\n\t\t\t\u00bfHas olvidado tu contrase\u00f1a?\t\t<\/a>\n\t<\/div>\n\n\t\t\t<\/form>\n\t<\/div>\n<\/div>\n<style>\n\t\t\t.um-435.um {\n\t\t\tmax-width: 450px;\n\t\t}\n\t\t<\/style>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-439","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/eledecolombia.com.co\/wordpress\/wp-json\/wp\/v2\/pages\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eledecolombia.com.co\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eledecolombia.com.co\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eledecolombia.com.co\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eledecolombia.com.co\/wordpress\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":5,"href":"https:\/\/eledecolombia.com.co\/wordpress\/wp-json\/wp\/v2\/pages\/439\/revisions"}],"predecessor-version":[{"id":1640,"href":"https:\/\/eledecolombia.com.co\/wordpress\/wp-json\/wp\/v2\/pages\/439\/revisions\/1640"}],"wp:attachment":[{"href":"https:\/\/eledecolombia.com.co\/wordpress\/wp-json\/wp\/v2\/media?parent=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}